{"id":14004,"date":"2023-05-23T13:46:46","date_gmt":"2023-05-23T13:46:46","guid":{"rendered":"https:\/\/www.atslifesciences.com\/soluzioni-di-automazione\/visione-e-test\/cortex-neo\/"},"modified":"2026-06-15T13:22:17","modified_gmt":"2026-06-15T13:22:17","slug":"cortex-neo","status":"publish","type":"page","link":"https:\/\/www.atslifesciences.com\/it\/soluzioni-diautomazione\/visione-e-test\/cortex-neo\/","title":{"rendered":"Cortex NEO"},"content":{"rendered":"\n<div class=\"atsls-secondary-hero\" id=\"atsls-secondary-hero-block_4335cf86d4f9d5b9fbda9f5d8d98b16c\">\n\n  <div class=\"inner-wrp\">\n\n    \n      <div class=\"background-wrp\" style=\"background-image: url(https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2024\/06\/ATS-Synergy-Panel_2-1.jpg);\">\n                  <div class=\"img-wrp\">\n            <img decoding=\"async\" src=\"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2024\/06\/ATS-Synergy-Panel_2-1.jpg\">\n          <\/div>\n              <\/div>\n\n    \n    <div class=\"container\">\n\n      <div class=\"row\">\n\n        <div class=\"col-md-5\">\n\n          <div class=\"sub-title\">\n            <p>Sistema di visione integrato all-in-one\u00a0<\/p>\n          <\/div>\n          \n          <div class=\"title-part\">\n            <h1>ATS CORTEX NEO<\/h1>\n          <\/div>\n\n          <div class=\"description\">\n            <p>Sistema di visione e software aperto per il coordinamento e il controllo delle telecamere e dei sistemi di illuminazione necessari per le ispezioni complesse, in grado di offrire convenienza, connettivit\u00e0 e personalizzazione<\/p>\n          <\/div>\n\n          \n        <\/div>\n        \n      <\/div>\n\n    <\/div>\n  \n  <\/div>\n\n<\/div>\n\n<style type=\"text\/css\">\n#atsls-secondary-hero-block_4335cf86d4f9d5b9fbda9f5d8d98b16c {\n  padding-top: 100px;\n  background-color: #0A2463;\n}\n\n#atsls-secondary-hero-block_4335cf86d4f9d5b9fbda9f5d8d98b16c .inner-wrp {\n  padding-top: 6rem;\n  padding-bottom: 6rem;\n  position: relative;\n}\n\n\n#atsls-secondary-hero-block_4335cf86d4f9d5b9fbda9f5d8d98b16c .inner-wrp .background-wrp {\n  background-repeat: no-repeat;\n  background-position: center;\n  background-size: cover;\n  position: relative;\n  width: 55%;\n  height: 100%;\n  position: absolute;\n  top: 0;\n  right: 0;\n  z-index: 1;\n  overflow: hidden;\n}\n#atsls-secondary-hero-block_4335cf86d4f9d5b9fbda9f5d8d98b16c .inner-wrp .background-wrp .img-wrp {\n  display: none;\n  position: relative;\n  height: 0;\n  width: 100%;\n  padding-bottom: 56.25%;\n  margin-bottom: 0px;\n  overflow: hidden;\n}\n#atsls-secondary-hero-block_4335cf86d4f9d5b9fbda9f5d8d98b16c .inner-wrp .background-wrp .img-wrp img {\n  position: absolute;\n  width: 100%;\n  height: 100%;\n  top: 0;\n  left: 0;\n  object-fit: cover;\n  object-position: center;\n}\n\n#atsls-secondary-hero-block_4335cf86d4f9d5b9fbda9f5d8d98b16c .inner-wrp .background-video-wrp {\n  background-repeat: no-repeat;\n  background-position: center;\n  background-size: cover;\n  position: relative;\n  width: 55%;\n  height: 100%;\n  position: absolute;\n  top: 0;\n  right: 0;\n  z-index: 1;\n  overflow: hidden;\n}\n#atsls-secondary-hero-block_4335cf86d4f9d5b9fbda9f5d8d98b16c .inner-wrp .background-video-wrp .video-wrp {\n  display: block;\n  position: relative;\n  height: 0;\n  width: 100%;\n  padding-bottom: 60%;\n  margin-bottom: 0px;\n  overflow: hidden;\n}\n#atsls-secondary-hero-block_4335cf86d4f9d5b9fbda9f5d8d98b16c .inner-wrp .background-video-wrp .video-wrp video {\n  position: absolute;\n  width: 100%;\n  height: 100%;\n  top: 0;\n  left: 0;\n  object-fit: cover;\n  object-position: center;\n}\n\n#atsls-secondary-hero-block_4335cf86d4f9d5b9fbda9f5d8d98b16c .container {\n  position: relative;\n  z-index: 2;\n}\n\n#atsls-secondary-hero-block_4335cf86d4f9d5b9fbda9f5d8d98b16c .inner-wrp::after {\n  content: \"\";\n  width: 65%;\n  height: 100%;\n  position: absolute;\n  top: 0;\n  left: -10%;\n  transform: skew(-20deg);\n  background-color: #0A2463;\n  border-right: 6px solid #41BFAC;\n  z-index: 1;\n}\n#atsls-secondary-hero-block_4335cf86d4f9d5b9fbda9f5d8d98b16c .title-part h1, #atsls-secondary-hero-block_4335cf86d4f9d5b9fbda9f5d8d98b16c .title-part .h1 {\n  color: #FFF;\n  font-family: \"Roboto\", sans-serif;\n  font-size: 48px;\n  font-style: normal;\n  font-weight: 500;\n  line-height: normal;\n  margin-bottom: 15px;\n}\n.single-news-page #atsls-secondary-hero-block_4335cf86d4f9d5b9fbda9f5d8d98b16c .title-part h1 {\n  font-size: 28px;\n  text-transform: unset;\n}\n#atsls-secondary-hero-block_4335cf86d4f9d5b9fbda9f5d8d98b16c .sub-title p {\n  color: #9ACD4F;\n  \/* Subtitle *\/\n  font-family: \"Roboto\", sans-serif;\n  font-size: 16px;\n  font-style: normal;\n  font-weight: 500;\n  line-height: 140%; \/* 22.4px *\/\n  margin-bottom: 5px;\n}\n#atsls-secondary-hero-block_4335cf86d4f9d5b9fbda9f5d8d98b16c .description p {\n  color: #FFF;\n  \/* Paragraph *\/\n  font-family: \"Roboto\", sans-serif;\n  font-size: 18px;\n  font-style: normal;\n  font-weight: 400;\n  line-height: 140%; \/* 25.2px *\/\n}\n#atsls-secondary-hero-block_4335cf86d4f9d5b9fbda9f5d8d98b16c .cta-btn {\n  padding-top: 15px;\n}\n#atsls-secondary-hero-block_4335cf86d4f9d5b9fbda9f5d8d98b16c .cta-btn a {\n  position: relative;\n  padding: 10px 40px !important;\n  transition: all ease 0.3s !important;\n  background-color: #9ACD4F;\n  text-decoration: none;\n  color: #071630;\n  font-size: 18px;\n}\n\n#atsls-secondary-hero-block_4335cf86d4f9d5b9fbda9f5d8d98b16c .cta-btn a:before {\n  content: \"\" !important;\n  background-image: url('https:\/\/www.atslifesciences.com\/wp-content\/themes\/atsls-2024\/assets\/btn-icon.svg');\n  width: 30px;\n  height: 30px;\n  background-repeat: no-repeat;\n  background-position: center;\n  background-size: 30px 30px;\n  position: absolute;\n  top: 8px !important;\n  left: 20px !important;\n  opacity: 0;\n  transition: all ease 0.3s;\n}\n\n#atsls-secondary-hero-block_4335cf86d4f9d5b9fbda9f5d8d98b16c .cta-btn a:hover {\n  padding-left: 60px !important;\n  padding-right: 20px !important;\n}\n#atsls-secondary-hero-block_4335cf86d4f9d5b9fbda9f5d8d98b16c .cta-btn a:hover:before {\n  opacity: 1;\n}\n\n\n@media (max-width: 768px) {\n  #atsls-secondary-hero-block_4335cf86d4f9d5b9fbda9f5d8d98b16c {\n    padding-top: 79px;\n  }\n  #atsls-secondary-hero-block_4335cf86d4f9d5b9fbda9f5d8d98b16c .title-part h1 {\n    font-size: 30px;\n  }\n  #atsls-secondary-hero-block_4335cf86d4f9d5b9fbda9f5d8d98b16c .inner-wrp {\n    padding-top: 0px;\n    padding-bottom: 32px;\n  }\n  #atsls-secondary-hero-block_4335cf86d4f9d5b9fbda9f5d8d98b16c .inner-wrp::after {\n    width: 100%;\n    height: 100%;\n    left: 0;\n    top: 0;\n    transform: unset;\n    border: none;\n  }\n\n  #atsls-secondary-hero-block_4335cf86d4f9d5b9fbda9f5d8d98b16c .inner-wrp .background-wrp {\n    width: 100%;\n    position: relative;\n    height: auto;\n    z-index: 2;\n    margin-bottom: 30px;\n  }\n  #atsls-secondary-hero-block_4335cf86d4f9d5b9fbda9f5d8d98b16c .inner-wrp .background-wrp .img-wrp {\n    display: block;\n  }\n  #atsls-secondary-hero-block_4335cf86d4f9d5b9fbda9f5d8d98b16c .inner-wrp .background-video-wrp {\n    width: 100%;\n    position: relative;\n    height: auto;\n    z-index: 2;\n    margin-bottom: 30px;\n  }\n}\n\n<\/style>\n\n\n<div class=\"gb-container gb-container-5ed2b593\"><div class=\"gb-inside-container\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-5720446a\">\n<div class=\"gb-grid-column gb-grid-column-cceefbc0\"><div class=\"gb-container gb-container-cceefbc0\"><div class=\"gb-inside-container\">\n\n<figure class=\"gb-block-image gb-block-image-02790f18\"><img decoding=\"async\" loading=\"lazy\" width=\"1400\" height=\"800\" class=\"gb-image gb-image-02790f18\" src=\"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2023\/05\/cortex.png\" alt=\"\" title=\"cortex\" srcset=\"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2023\/05\/cortex.png 1400w, https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2023\/05\/cortex.png?resize=300,171 300w, https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2023\/05\/cortex.png?resize=768,439 768w, https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2023\/05\/cortex.png?resize=1024,585 1024w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><\/figure>\n\n<\/div><\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-def75a10\"><div class=\"gb-container gb-container-def75a10\"><div class=\"gb-inside-container\">\n\n<h2 class=\"gb-headline gb-headline-b9f77f65 gb-headline-text\">ATS Cortex NEO<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Riducete i tempi di integrazione con una soluzione di visione completa di hardware e software standardizzati.<\/p>\n\n\n\n<ul style=\"letter-spacing:0px\" class=\"wp-block-list has-black-color has-text-color\">\n<li>Scalabile tra i tipi di applicazione e i livelli di complessit\u00e0<\/li>\n\n\n\n<li>Potente kit di strumenti incluso<\/li>\n\n\n\n<li>Sviluppo rapido delle applicazioni<\/li>\n<\/ul>\n\n\n<div class=\"gb-button-wrapper gb-button-wrapper-739011f7\">\n\n<a class=\"gb-button gb-button-e458903b gb-button-text atsls-btn\" href=\"https:\/\/go.atsautomation.com\/l\/651873\/2025-11-18\/h8bw8j\/651873\/1763481982ue1UTkOg\/Factsheet___Cortex_Neo_v3_final.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Cortex-NEO 1200 Series<\/a>\n\n<\/div>\n\n<div class=\"gb-button-wrapper gb-button-wrapper-ab744603\">\n\n<a class=\"gb-button gb-button-e2f34b46 gb-button-text atsls-btn\" href=\"https:\/\/go.atsautomation.com\/l\/651873\/2026-06-15\/h8nldq\/651873\/1781529137JuPvmRnB\/Factsheet___Cortex_Neo_June_2026.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Cortex-NEO 1300 Series<\/a>\n\n<\/div>\n<\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"gb-container gb-container-c3b6b6f0 segment-icons-wrp\"><div class=\"gb-inside-container\">\n<div class=\"gb-container gb-container-94e352f0\"><div class=\"gb-inside-container\">\n\n<h2 class=\"gb-headline gb-headline-22ade782 gb-headline-text\">Vantaggi principali<\/h2>\n\n\n\n<p class=\"gb-headline gb-headline-c786cebb gb-headline-text gb-headline-paragraph-global\">Una soluzione di visione integrata completa di hardware e software standardizzati.<\/p>\n\n<\/div><\/div>\n\n<div class=\"gb-grid-wrapper gb-grid-wrapper-a9e6320c automation-solutions-cards\">\n<div class=\"gb-grid-column gb-grid-column-55870fa8\"><div class=\"gb-container gb-container-55870fa8\"><div class=\"gb-inside-container\">\n\n<h3 class=\"gb-headline gb-headline-b29ab1f2 gb-headline-text\"><img loading=\"lazy\" decoding=\"async\" width=\"70\" height=\"29\" class=\"wp-image-18122\" style=\"width: 70px;\" src=\"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2024\/06\/lines.svg\" alt=\"\"> Computer di elaborazione<\/h3>\n\n\n\n<p class=\"gb-headline gb-headline-792feee8 gb-headline-text\">Pu\u00f2 comunicare con un controllore logico programmabile (PLC) attraverso un\u2019ampia variet\u00e0 di interfacce per bus di campo.<\/p>\n\n<\/div><\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-caede995\"><div class=\"gb-container gb-container-caede995\"><div class=\"gb-inside-container\">\n\n<h3 class=\"gb-headline gb-headline-ff16d6b0 gb-headline-text\"><img loading=\"lazy\" decoding=\"async\" width=\"70\" height=\"29\" class=\"wp-image-18122\" style=\"width: 70px;\" src=\"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2024\/06\/lines.svg\" alt=\"\"> Storage flessibile<\/h3>\n\n\n\n<p class=\"gb-headline gb-headline-0dd17fec gb-headline-text\">Livelli diversi di storage e RAM in base alla configurazione del modello per adattarsi a qualsiasi applicazione.&nbsp;<\/p>\n\n<\/div><\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-72e0f1a7\"><div class=\"gb-container gb-container-72e0f1a7\"><div class=\"gb-inside-container\">\n\n<h3 class=\"gb-headline gb-headline-270089b4 gb-headline-text\"><img loading=\"lazy\" decoding=\"async\" width=\"70\" height=\"29\" class=\"wp-image-18122\" style=\"width: 70px;\" src=\"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2024\/06\/lines.svg\" alt=\"\"> Potenza della telecamera<\/h3>\n\n\n\n<p class=\"gb-headline gb-headline-a6e7a25c gb-headline-text\">Pu\u00f2 collegarsi a un massimo di quattro (4) telecamere GigE Power Over Ethernet (PoE).<\/p>\n\n<\/div><\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-9dba5739\"><div class=\"gb-container gb-container-9dba5739\"><div class=\"gb-inside-container\">\n\n<h3 class=\"gb-headline gb-headline-a367a1c3 gb-headline-text\"><img loading=\"lazy\" decoding=\"async\" width=\"70\" height=\"29\" class=\"wp-image-18122\" style=\"width: 70px;\" src=\"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2024\/06\/lines.svg\" alt=\"\"> Funzionalit\u00e0 plug-and-play<\/h3>\n\n\n\n<p class=\"gb-headline gb-headline-93d024d6 gb-headline-text\">I connettori USB sono connettori standard USB 3.1 plug-and-play utilizzati per il dispositivo di backup integrato e altre periferiche, ad esempio tastiera e mouse.<\/p>\n\n<\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"gb-container gb-container-0fdfa3be\"><div class=\"gb-inside-container\">\n\n<h2 class=\"gb-headline gb-headline-9867b477 gb-headline-text\">Altre soluzioni di visione e test<\/h2>\n\n\n<div class=\"gb-grid-wrapper gb-grid-wrapper-c6daeb78 segments-card\">\n<div class=\"gb-grid-column gb-grid-column-fc0f74f5\"><div class=\"gb-container gb-container-fc0f74f5 card-item\"><div class=\"gb-inside-container\">\n\n<figure class=\"gb-block-image gb-block-image-d2a8fd54\"><img decoding=\"async\" loading=\"lazy\" width=\"533\" height=\"398\" class=\"gb-image gb-image-d2a8fd54\" src=\"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2023\/05\/Smartvision-screen-image.png\" alt=\"\" title=\"Smartvision screen image\" srcset=\"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2023\/05\/Smartvision-screen-image.png 533w, https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2023\/05\/Smartvision-screen-image.png?resize=300,224 300w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/><\/figure>\n\n\n\n<h3 class=\"gb-headline gb-headline-8bed751e gb-headline-text\"><strong>SmartVision\u2122<\/strong><\/h3>\n\n\n\n<p class=\"gb-headline gb-headline-181e7e46 gb-headline-text\">Il software SmartVision \u00e8 un sistema di visione altamente scalabile basato su PC che combina un motore di visione ad alte prestazioni indipendente dalla piattaforma e un\u2019interfaccia standard di facile utilizzo.<\/p>\n\n\n<div class=\"gb-button-wrapper gb-button-wrapper-4b25f6bd\">\n\n<a class=\"gb-button gb-button-ef9ca3f6 gb-button-text\" href=\"https:\/\/www.atslifesciences.com\/it\/soluzioni-di-automazione\/visione-e-test\/smartvision\/\">Per saperne di pi\u00f9<\/a>\n\n<\/div>\n<\/div><\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-2eb2437b\"><div class=\"gb-container gb-container-2eb2437b card-item\"><div class=\"gb-inside-container\">\n\n<figure class=\"gb-block-image gb-block-image-941ce3ae\"><img decoding=\"async\" loading=\"lazy\" width=\"727\" height=\"485\" class=\"gb-image gb-image-941ce3ae\" src=\"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2023\/05\/PharmaScan.png\" alt=\"\" title=\"PharmaScan\" srcset=\"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2023\/05\/PharmaScan.png 727w, https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2023\/05\/PharmaScan.png?resize=300,200 300w\" sizes=\"auto, (max-width: 727px) 100vw, 727px\" \/><\/figure>\n\n\n\n<h3 class=\"gb-headline gb-headline-deafe9db gb-headline-text\"><strong>PharmaScan\u2122&nbsp;<\/strong><\/h3>\n\n\n\n<p class=\"gb-headline gb-headline-4765099c gb-headline-text\">La famiglia di piattaforme di ispezione avanzate PharmaScan\u2122 \u00e8 stata progettata per soddisfare i pi\u00f9 elevati standard dell\u2019industria farmaceutica per i prodotti liquidi o liofilizzati. \u00c8 in grado di controllare pi\u00f9 criteri di difetto.<\/p>\n\n\n<div class=\"gb-button-wrapper gb-button-wrapper-cf9f5abb\">\n\n<a class=\"gb-button gb-button-f95c3eb5 gb-button-text\" href=\"https:\/\/www.atslifesciences.com\/it\/soluzioni-di-automazione\/pharmascan\/\">Per saperne di pi\u00f9<\/a>\n\n<\/div>\n<\/div><\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-597b8f59\"><div class=\"gb-container gb-container-597b8f59 card-item\"><div class=\"gb-inside-container\">\n\n<figure class=\"gb-block-image gb-block-image-d6a4dee0\"><img decoding=\"async\" loading=\"lazy\" width=\"918\" height=\"554\" class=\"gb-image gb-image-d6a4dee0\" src=\"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2023\/05\/bluetooth-1.png\" alt=\"\" title=\"bluetooth\" srcset=\"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2023\/05\/bluetooth-1.png 918w, https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2023\/05\/bluetooth-1.png?resize=300,181 300w, https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2023\/05\/bluetooth-1.png?resize=768,463 768w\" sizes=\"auto, (max-width: 918px) 100vw, 918px\" \/><\/figure>\n\n\n\n<h3 class=\"gb-headline gb-headline-ced2a42e gb-headline-text\"><strong>Bluetooth\u00ae&nbsp;<\/strong><\/h3>\n\n\n\n<p class=\"gb-headline gb-headline-0772a95b gb-headline-text\">Verificate e convalidate la corretta trasmissione dei dati e la funzionalit\u00e0 dei vostri dispositivi medici e diagnostici intelligenti dotati di Bluetooth\u00ae. Co-sviluppiamo test di funzionalit\u00e0 Bluetooth\u00ae su misura per i vostri requisiti specifici di prodotto e di processo.<\/p>\n\n\n<div class=\"gb-button-wrapper gb-button-wrapper-72112fde\">\n\n<a class=\"gb-button gb-button-b0c92da7 gb-button-text\" href=\"https:\/\/www.atslifesciences.com\/bluetooth-functionality-testing\/\">Per saperne di pi\u00f9<\/a>\n\n<\/div>\n<\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"gb-container gb-container-8f2b40f6 alignfull\"><div class=\"gb-inside-container\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-e38c66c3\">\n<div class=\"gb-grid-column gb-grid-column-f4ea0eac\"><div class=\"gb-container gb-container-f4ea0eac\"><div class=\"gb-inside-container\">\n\n<h2 class=\"gb-headline gb-headline-5adb5275 gb-headline-text\">Sistema di visione integrato all-in-one<\/h2>\n\n\n\n<p class=\"has-white-color has-text-color wp-block-paragraph\">Per le ispezioni complesse, offriamo convenienza, connettivit\u00e0 e personalizzazione. Fateci sapere come possiamo esservi utili.<\/p>\n\n\n<div class=\"gb-button-wrapper gb-button-wrapper-ce2c7be5\">\n\n<a class=\"gb-button gb-button-fc3d0119 gb-button-text atsls-btn atsls-modal-btn\" href=\"#\" data-id=\"atsls-modal-medium\">Contattaci<\/a>\n\n<\/div>\n<\/div><\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-6a420282\"><div class=\"gb-container gb-container-6a420282\"><div class=\"gb-inside-container\"><\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"gb-container gb-container-c4f2ffb8 atsls-modal atsls-modal-medium alignfull\" data-id=\"atsls-modal-medium\"><div class=\"gb-inside-container\">\n\n<h2 class=\"gb-headline gb-headline-63a91292 gb-headline-text\">Contattaci<\/h2>\n\n\n\n\n<!-- iframe plugin v.6.0 wordpress.org\/plugins\/iframe\/ -->\n<iframe loading=\"lazy\" data-cookieconsent=\"ignore\" id=\"pardot-iframe\" style=\"border: 0;\" src=\"https:\/\/go.atsautomation.com\/l\/651873\/2023-04-05\/h5mk32?Source_Page=cortex-neo\" width=\"100%\" frameborder=\"0\" height=\"500\" scrolling=\"yes\" class=\"iframe-class\"><\/iframe>\n\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Vantaggi principali Una soluzione di visione integrata completa di hardware e software standardizzati. Altre soluzioni di visione e test Contattaci<\/p>\n","protected":false},"author":420,"featured_media":0,"parent":13956,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/empty.php","meta":{"_acf_changed":false,"_cr_original_post":"","_cr_replace_post_id":"","_cr_replacing_post_id":"","inline_featured_image":false,"cover_image":0,"footnotes":""},"coauthors":[126],"class_list":["post-14004","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cortex NEO - ATS Life Sciences<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.atslifesciences.com\/it\/soluzioni-diautomazione\/visione-e-test\/cortex-neo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cortex NEO\" \/>\n<meta property=\"og:description\" content=\"Vantaggi principali Una soluzione di visione integrata completa di hardware e software standardizzati. Altre soluzioni di visione e test Contattaci\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.atslifesciences.com\/it\/soluzioni-diautomazione\/visione-e-test\/cortex-neo\/\" \/>\n<meta property=\"og:site_name\" content=\"ATS Life Sciences\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-15T13:22:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2023\/05\/cortex.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"dave\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.atslifesciences.com\\\/it\\\/soluzioni-diautomazione\\\/visione-e-test\\\/cortex-neo\\\/\",\"url\":\"https:\\\/\\\/www.atslifesciences.com\\\/it\\\/soluzioni-diautomazione\\\/visione-e-test\\\/cortex-neo\\\/\",\"name\":\"Cortex NEO - ATS Life Sciences\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.atslifesciences.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.atslifesciences.com\\\/it\\\/soluzioni-diautomazione\\\/visione-e-test\\\/cortex-neo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.atslifesciences.com\\\/it\\\/soluzioni-diautomazione\\\/visione-e-test\\\/cortex-neo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.atslifesciences.com\\\/wp-content\\\/uploads\\\/sites\\\/63\\\/2023\\\/05\\\/cortex.png\",\"datePublished\":\"2023-05-23T13:46:46+00:00\",\"dateModified\":\"2026-06-15T13:22:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.atslifesciences.com\\\/it\\\/soluzioni-diautomazione\\\/visione-e-test\\\/cortex-neo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.atslifesciences.com\\\/it\\\/soluzioni-diautomazione\\\/visione-e-test\\\/cortex-neo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.atslifesciences.com\\\/it\\\/soluzioni-diautomazione\\\/visione-e-test\\\/cortex-neo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.atslifesciences.com\\\/wp-content\\\/uploads\\\/sites\\\/63\\\/2023\\\/05\\\/cortex.png\",\"contentUrl\":\"https:\\\/\\\/www.atslifesciences.com\\\/wp-content\\\/uploads\\\/sites\\\/63\\\/2023\\\/05\\\/cortex.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.atslifesciences.com\\\/it\\\/soluzioni-diautomazione\\\/visione-e-test\\\/cortex-neo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.atslifesciences.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SOLUZIONI DI AUTOMAZIONE\",\"item\":\"https:\\\/\\\/www.atslifesciences.com\\\/it\\\/soluzioni-diautomazione\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"VISIONE E TEST\",\"item\":\"https:\\\/\\\/www.atslifesciences.com\\\/it\\\/soluzioni-di-automazione__trashed\\\/visione-e-test\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Cortex NEO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.atslifesciences.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.atslifesciences.com\\\/it\\\/\",\"name\":\"ATS Life Sciences\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.atslifesciences.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cortex NEO - ATS Life Sciences","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.atslifesciences.com\/it\/soluzioni-diautomazione\/visione-e-test\/cortex-neo\/","og_locale":"it_IT","og_type":"article","og_title":"Cortex NEO","og_description":"Vantaggi principali Una soluzione di visione integrata completa di hardware e software standardizzati. Altre soluzioni di visione e test Contattaci","og_url":"https:\/\/www.atslifesciences.com\/it\/soluzioni-diautomazione\/visione-e-test\/cortex-neo\/","og_site_name":"ATS Life Sciences","article_modified_time":"2026-06-15T13:22:17+00:00","og_image":[{"url":"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2023\/05\/cortex.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuti","Written by":"dave"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.atslifesciences.com\/it\/soluzioni-diautomazione\/visione-e-test\/cortex-neo\/","url":"https:\/\/www.atslifesciences.com\/it\/soluzioni-diautomazione\/visione-e-test\/cortex-neo\/","name":"Cortex NEO - ATS Life Sciences","isPartOf":{"@id":"https:\/\/www.atslifesciences.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.atslifesciences.com\/it\/soluzioni-diautomazione\/visione-e-test\/cortex-neo\/#primaryimage"},"image":{"@id":"https:\/\/www.atslifesciences.com\/it\/soluzioni-diautomazione\/visione-e-test\/cortex-neo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2023\/05\/cortex.png","datePublished":"2023-05-23T13:46:46+00:00","dateModified":"2026-06-15T13:22:17+00:00","breadcrumb":{"@id":"https:\/\/www.atslifesciences.com\/it\/soluzioni-diautomazione\/visione-e-test\/cortex-neo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.atslifesciences.com\/it\/soluzioni-diautomazione\/visione-e-test\/cortex-neo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.atslifesciences.com\/it\/soluzioni-diautomazione\/visione-e-test\/cortex-neo\/#primaryimage","url":"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2023\/05\/cortex.png","contentUrl":"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2023\/05\/cortex.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.atslifesciences.com\/it\/soluzioni-diautomazione\/visione-e-test\/cortex-neo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.atslifesciences.com\/it\/"},{"@type":"ListItem","position":2,"name":"SOLUZIONI DI AUTOMAZIONE","item":"https:\/\/www.atslifesciences.com\/it\/soluzioni-diautomazione\/"},{"@type":"ListItem","position":3,"name":"VISIONE E TEST","item":"https:\/\/www.atslifesciences.com\/it\/soluzioni-di-automazione__trashed\/visione-e-test\/"},{"@type":"ListItem","position":4,"name":"Cortex NEO"}]},{"@type":"WebSite","@id":"https:\/\/www.atslifesciences.com\/it\/#website","url":"https:\/\/www.atslifesciences.com\/it\/","name":"ATS Life Sciences","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.atslifesciences.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"acf":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.atslifesciences.com\/it\/wp-json\/wp\/v2\/pages\/14004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.atslifesciences.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.atslifesciences.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.atslifesciences.com\/it\/wp-json\/wp\/v2\/users\/420"}],"replies":[{"embeddable":true,"href":"https:\/\/www.atslifesciences.com\/it\/wp-json\/wp\/v2\/comments?post=14004"}],"version-history":[{"count":6,"href":"https:\/\/www.atslifesciences.com\/it\/wp-json\/wp\/v2\/pages\/14004\/revisions"}],"predecessor-version":[{"id":27617,"href":"https:\/\/www.atslifesciences.com\/it\/wp-json\/wp\/v2\/pages\/14004\/revisions\/27617"}],"up":[{"embeddable":true,"href":"https:\/\/www.atslifesciences.com\/it\/wp-json\/wp\/v2\/pages\/13956"}],"wp:attachment":[{"href":"https:\/\/www.atslifesciences.com\/it\/wp-json\/wp\/v2\/media?parent=14004"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.atslifesciences.com\/it\/wp-json\/wp\/v2\/coauthors?post=14004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}