{"id":13470,"date":"2023-03-28T15:25:53","date_gmt":"2023-03-28T15:25:53","guid":{"rendered":"https:\/\/www.atslifesciences.com\/lenti-a-contatto-prodotti-oftalmici\/"},"modified":"2025-11-27T17:30:14","modified_gmt":"2025-11-27T17:30:14","slug":"lenti-a-contatto-prodotti-oftalmici","status":"publish","type":"page","link":"https:\/\/www.atslifesciences.com\/it\/segmenti-di-mercato-che-serviamo\/dispositivi-medici\/lenti-a-contatto-prodotti-oftalmici\/","title":{"rendered":"LENTI A CONTATTO\/PRODOTTI OFTALMICI"},"content":{"rendered":"\n<div class=\"atsls-secondary-hero\" id=\"atsls-secondary-hero-block_66f65819aa6aa2cc943084c87f84c5cc\">\n\n  <div class=\"inner-wrp\">\n\n    \n      <div class=\"background-wrp\" style=\"background-image: url(https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2024\/06\/contact-lenses.jpg);\">\n                  <div class=\"img-wrp\">\n            <img decoding=\"async\" src=\"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2024\/06\/contact-lenses.jpg\">\n          <\/div>\n              <\/div>\n\n    \n    <div class=\"container\">\n\n      <div class=\"row\">\n\n        <div class=\"col-md-5\">\n\n          <div class=\"sub-title\">\n            <p><\/p>\n          <\/div>\n          \n          <div class=\"title-part\">\n            <h1>LENTI A CONTATTO\/PRODOTTI OFTALMICI<\/h1>\n          <\/div>\n\n          <div class=\"description\">\n            <p>Gli analisti prevedono che il mercato delle lenti a contatto cosmetiche e graduate sia destinato a crescere di ~124% entro il 2025.\u00a0<strong>Sei pronto?<\/strong><\/p>\n          <\/div>\n\n          \n        <\/div>\n        \n      <\/div>\n\n    <\/div>\n  \n  <\/div>\n\n<\/div>\n\n<style type=\"text\/css\">\n#atsls-secondary-hero-block_66f65819aa6aa2cc943084c87f84c5cc {\n  padding-top: 100px;\n  background-color: #0A2463;\n}\n\n#atsls-secondary-hero-block_66f65819aa6aa2cc943084c87f84c5cc .inner-wrp {\n  padding-top: 6rem;\n  padding-bottom: 6rem;\n  position: relative;\n}\n\n\n#atsls-secondary-hero-block_66f65819aa6aa2cc943084c87f84c5cc .inner-wrp .background-wrp {\n  background-repeat: no-repeat;\n  background-position: center;\n  background-size: cover;\n  position: relative;\n  width: 55%;\n  height: 100%;\n  position: absolute;\n  top: 0;\n  right: 0;\n  z-index: 1;\n  overflow: hidden;\n}\n#atsls-secondary-hero-block_66f65819aa6aa2cc943084c87f84c5cc .inner-wrp .background-wrp .img-wrp {\n  display: none;\n  position: relative;\n  height: 0;\n  width: 100%;\n  padding-bottom: 56.25%;\n  margin-bottom: 0px;\n  overflow: hidden;\n}\n#atsls-secondary-hero-block_66f65819aa6aa2cc943084c87f84c5cc .inner-wrp .background-wrp .img-wrp img {\n  position: absolute;\n  width: 100%;\n  height: 100%;\n  top: 0;\n  left: 0;\n  object-fit: cover;\n  object-position: center;\n}\n\n#atsls-secondary-hero-block_66f65819aa6aa2cc943084c87f84c5cc .inner-wrp .background-video-wrp {\n  background-repeat: no-repeat;\n  background-position: center;\n  background-size: cover;\n  position: relative;\n  width: 55%;\n  height: 100%;\n  position: absolute;\n  top: 0;\n  right: 0;\n  z-index: 1;\n  overflow: hidden;\n}\n#atsls-secondary-hero-block_66f65819aa6aa2cc943084c87f84c5cc .inner-wrp .background-video-wrp .video-wrp {\n  display: block;\n  position: relative;\n  height: 0;\n  width: 100%;\n  padding-bottom: 60%;\n  margin-bottom: 0px;\n  overflow: hidden;\n}\n#atsls-secondary-hero-block_66f65819aa6aa2cc943084c87f84c5cc .inner-wrp .background-video-wrp .video-wrp video {\n  position: absolute;\n  width: 100%;\n  height: 100%;\n  top: 0;\n  left: 0;\n  object-fit: cover;\n  object-position: center;\n}\n\n#atsls-secondary-hero-block_66f65819aa6aa2cc943084c87f84c5cc .container {\n  position: relative;\n  z-index: 2;\n}\n\n#atsls-secondary-hero-block_66f65819aa6aa2cc943084c87f84c5cc .inner-wrp::after {\n  content: \"\";\n  width: 65%;\n  height: 100%;\n  position: absolute;\n  top: 0;\n  left: -10%;\n  transform: skew(-20deg);\n  background-color: #0A2463;\n  border-right: 6px solid #41BFAC;\n  z-index: 1;\n}\n#atsls-secondary-hero-block_66f65819aa6aa2cc943084c87f84c5cc .title-part h1, #atsls-secondary-hero-block_66f65819aa6aa2cc943084c87f84c5cc .title-part .h1 {\n  color: #FFF;\n  font-family: \"Roboto\", sans-serif;\n  font-size: 48px;\n  font-style: normal;\n  font-weight: 500;\n  line-height: normal;\n  margin-bottom: 15px;\n}\n.single-news-page #atsls-secondary-hero-block_66f65819aa6aa2cc943084c87f84c5cc .title-part h1 {\n  font-size: 28px;\n  text-transform: unset;\n}\n#atsls-secondary-hero-block_66f65819aa6aa2cc943084c87f84c5cc .sub-title p {\n  color: #9ACD4F;\n  \/* Subtitle *\/\n  font-family: \"Roboto\", sans-serif;\n  font-size: 16px;\n  font-style: normal;\n  font-weight: 500;\n  line-height: 140%; \/* 22.4px *\/\n  margin-bottom: 5px;\n}\n#atsls-secondary-hero-block_66f65819aa6aa2cc943084c87f84c5cc .description p {\n  color: #FFF;\n  \/* Paragraph *\/\n  font-family: \"Roboto\", sans-serif;\n  font-size: 18px;\n  font-style: normal;\n  font-weight: 400;\n  line-height: 140%; \/* 25.2px *\/\n}\n#atsls-secondary-hero-block_66f65819aa6aa2cc943084c87f84c5cc .cta-btn {\n  padding-top: 15px;\n}\n#atsls-secondary-hero-block_66f65819aa6aa2cc943084c87f84c5cc .cta-btn a {\n  position: relative;\n  padding: 10px 40px !important;\n  transition: all ease 0.3s !important;\n  background-color: #9ACD4F;\n  text-decoration: none;\n  color: #071630;\n  font-size: 18px;\n}\n\n#atsls-secondary-hero-block_66f65819aa6aa2cc943084c87f84c5cc .cta-btn a:before {\n  content: \"\" !important;\n  background-image: url('https:\/\/www.atslifesciences.com\/wp-content\/themes\/atsls-2024\/assets\/btn-icon.svg');\n  width: 30px;\n  height: 30px;\n  background-repeat: no-repeat;\n  background-position: center;\n  background-size: 30px 30px;\n  position: absolute;\n  top: 8px !important;\n  left: 20px !important;\n  opacity: 0;\n  transition: all ease 0.3s;\n}\n\n#atsls-secondary-hero-block_66f65819aa6aa2cc943084c87f84c5cc .cta-btn a:hover {\n  padding-left: 60px !important;\n  padding-right: 20px !important;\n}\n#atsls-secondary-hero-block_66f65819aa6aa2cc943084c87f84c5cc .cta-btn a:hover:before {\n  opacity: 1;\n}\n\n\n@media (max-width: 768px) {\n  #atsls-secondary-hero-block_66f65819aa6aa2cc943084c87f84c5cc {\n    padding-top: 79px;\n  }\n  #atsls-secondary-hero-block_66f65819aa6aa2cc943084c87f84c5cc .title-part h1 {\n    font-size: 30px;\n  }\n  #atsls-secondary-hero-block_66f65819aa6aa2cc943084c87f84c5cc .inner-wrp {\n    padding-top: 0px;\n    padding-bottom: 32px;\n  }\n  #atsls-secondary-hero-block_66f65819aa6aa2cc943084c87f84c5cc .inner-wrp::after {\n    width: 100%;\n    height: 100%;\n    left: 0;\n    top: 0;\n    transform: unset;\n    border: none;\n  }\n\n  #atsls-secondary-hero-block_66f65819aa6aa2cc943084c87f84c5cc .inner-wrp .background-wrp {\n    width: 100%;\n    position: relative;\n    height: auto;\n    z-index: 2;\n    margin-bottom: 30px;\n  }\n  #atsls-secondary-hero-block_66f65819aa6aa2cc943084c87f84c5cc .inner-wrp .background-wrp .img-wrp {\n    display: block;\n  }\n  #atsls-secondary-hero-block_66f65819aa6aa2cc943084c87f84c5cc .inner-wrp .background-video-wrp {\n    width: 100%;\n    position: relative;\n    height: auto;\n    z-index: 2;\n    margin-bottom: 30px;\n  }\n}\n\n<\/style>\n\n\n<div class=\"gb-container gb-container-79b8d587\"><div class=\"gb-inside-container\">\n\n<h2 class=\"gb-headline gb-headline-5a5214ce gb-headline-text\">Take this short quiz below to find out!<\/h2>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\"><strong>6 to 7 points<\/strong> \u2013 Your existing production seems to be meeting your needs for the most part. Stay connected to see which developments can keep you competitive.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>8 to 9 points<\/strong> \u2013 It seems you have some areas of concern. We&#8217;d be happy to discuss options to address specific opportunities that can help improve productivity in the short term.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Da 10 a 12 punti<\/strong>: le tue risposte suggeriscono che la linea esistente non ti rende competitivo. Programmiamo una revisione per parlare della soluzione che ti aiuter\u00e0 a raggiungere i tuoi obiettivi. \u00a0<\/p>\n\n\n<div class=\"gb-button-wrapper gb-button-wrapper-739011f7\">\n\n<a class=\"gb-button gb-button-e458903b gb-button-text atsls-btn atsls-modal-btn\" href=\"#\" data-id=\"atsls-modal-medium2\">TAKE QUIZ<\/a>\n\n<\/div>\n<\/div><\/div>\n\n<div class=\"gb-container gb-container-c4f2ffb8 atsls-modal atsls-modal-medium alignfull\" data-id=\"atsls-modal-medium2\"><div class=\"gb-inside-container\">\n\n<h2 class=\"gb-headline gb-headline-63a91292 gb-headline-text\">TAKE THE QUIZ<\/h2>\n\n\n\n<script>(function(t,e,s,n){var o,a,c;t.SMCX=t.SMCX||[],e.getElementById(n)||(o=e.getElementsByTagName(s),a=o[o.length-1],c=e.createElement(s),c.type=\"text\/javascript\",c.async=!0,c.id=n,c.src=\"https:\/\/widget.surveymonkey.com\/collect\/website\/js\/tRaiETqnLgj758hTBazgd59xLoA9gERmEx_2BxmBT7IdlloO0rrfeRiNDN0IxID_2BSi.js\",a.parentNode.insertBefore(c,a))})(window,document,\"script\",\"smcx-sdk\");<\/script>\n\n<\/div><\/div>\n\n<div class=\"gb-container gb-container-e9b7c94f alignfull\"><div class=\"gb-inside-container\">\n\n<h2 class=\"gb-headline gb-headline-bb9b756f gb-headline-text\">Collaborando con i pi\u00f9 importanti produttori siamo in grado di aiutarti a:<\/h2>\n\n\n<div class=\"gb-grid-wrapper gb-grid-wrapper-a9e6320c automation-solutions-cards\">\n<div class=\"gb-grid-column gb-grid-column-55870fa8\"><div class=\"gb-container gb-container-55870fa8\"><div class=\"gb-inside-container\">\n\n<h3 class=\"gb-headline gb-headline-b29ab1f2 gb-headline-text\"><img loading=\"lazy\" decoding=\"async\" width=\"70\" height=\"29\" class=\"wp-image-18122\" style=\"width: 70px;\" src=\"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2024\/06\/lines.svg\" alt=\"\"> <img decoding=\"async\" class=\"wp-image-8478\" style=\"width: 111px\" src=\"\" alt=\"\"><img decoding=\"async\" class=\"wp-image-8478\" style=\"width: 111px\" src=\"\" alt=\"\">Pianificare e coordinare tutte le attivit\u00e0 necessarie<\/h3>\n\n<\/div><\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-caede995\"><div class=\"gb-container gb-container-caede995\"><div class=\"gb-inside-container\">\n\n<h3 class=\"gb-headline gb-headline-ff16d6b0 gb-headline-text\"><img loading=\"lazy\" decoding=\"async\" width=\"70\" height=\"29\" class=\"wp-image-18122\" style=\"width: 70px;\" src=\"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2024\/06\/lines.svg\" alt=\"\"> <img decoding=\"async\" class=\"wp-image-8478\" style=\"width: 111px\" src=\"\" alt=\"\">Garantire le risorse necessarie<\/h3>\n\n<\/div><\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-72e0f1a7\"><div class=\"gb-container gb-container-72e0f1a7\"><div class=\"gb-inside-container\">\n\n<h3 class=\"gb-headline gb-headline-270089b4 gb-headline-text\"><img loading=\"lazy\" decoding=\"async\" width=\"70\" height=\"29\" class=\"wp-image-18122\" style=\"width: 70px;\" src=\"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2024\/06\/lines.svg\" alt=\"\"> <img decoding=\"async\" class=\"wp-image-8478\" style=\"width: 111px\" src=\"\" alt=\"\"><img decoding=\"async\" class=\"wp-image-8478\" style=\"width: 111px\" src=\"\" alt=\"\">Mitigare il rischio<\/h3>\n\n<\/div><\/div><\/div>\n<\/div>\n\n\n<p class=\"has-white-color has-text-color wp-block-paragraph\">Soluzioni di produzione automatizzate per la fabbricazione di lenti a contatto correttive, cosmetiche o terapeutiche e prodotti oftalmici. Soluzioni chiavi in mano per ciascuna fase dalla produzione alla confezione pronta all\u2019uso, o isole di automazione per diminuire o aumentare le risorse in modo efficiente per soddisfare le richieste.<\/p>\n\n<\/div><\/div>\n\n<div class=\"gb-container gb-container-23fb8da5\"><div class=\"gb-inside-container\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-4c53bb5d\">\n<div class=\"gb-grid-column gb-grid-column-dae05dfe\"><div class=\"gb-container gb-container-dae05dfe\"><div class=\"gb-inside-container\">\n\n<h2 class=\"gb-headline gb-headline-ff53d3b3 gb-headline-text\">Soluzioni e validazione brevettati per la produzione oftalmica<\/h2>\n\n<\/div><\/div><\/div>\n<\/div>\n\n<div class=\"gb-grid-wrapper gb-grid-wrapper-986d76fe\">\n<div class=\"gb-grid-column gb-grid-column-ff2fbdf8\"><div class=\"gb-container gb-container-ff2fbdf8\"><div class=\"gb-inside-container\">\n\n<p class=\"gb-headline gb-headline-5acb5d67 gb-headline-text\">Macchine e processi affidabili, tra cui la validazione, sono la chiave per soddisfare la richiesta produttiva e contribuire al tuo OEE. ATS Life Sciences Systems vanta oltre vent\u2019anni di esperienza in soluzioni di produzione automatizzate di lenti a contatto integrate e progettate su misura.<\/p>\n\n\n\n<p class=\"gb-headline gb-headline-823d9142 gb-headline-text\">Ingegneria collaudata per l\u2019intera famiglia di prodotti, tra cui macchine multiuso ed erogazione di precisione per numerose ricette.<br>Soluzioni su misura per prodotti di nicchia.<\/p>\n\n\n\n<p class=\"gb-headline gb-headline-41e9dcf1 gb-headline-text\">La produzione \u00e8 supportata da una validazione rigorosa; gestione controllata e organizzazione fisica di numerose geometrie dello stampo elaborate nello stesso momento con tracciabilit\u00e0 opzionale della cronologia di produzione; linee finite con servizi di ciclo di vita completi.<\/p>\n\n<\/div><\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-25b4069d\"><div class=\"gb-container gb-container-25b4069d\"><div class=\"gb-inside-container\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-2336ca57\">\n<div class=\"gb-grid-column gb-grid-column-6da80967\"><div class=\"gb-container gb-container-6da80967\"><div class=\"gb-inside-container\">\n\n<ul class=\"wp-block-list\" style=\"font-size:18px\">\n<li>Soluzioni per volumi ridotti e altamente diversificati<\/li>\n\n\n\n<li>Scarico dello stampo ad alta velocit\u00e0<\/li>\n\n\n\n<li>Sistema di idratazione ed estrazione banco bagnato o asciutto<\/li>\n\n\n\n<li>Marcatura laser: identificazione permanente e leggibile dalla macchina<\/li>\n\n\n\n<li>Erogazione di monomeri in ambienti azotati: involucri sigillati e a tenuta stagna con controllo dei livelli di ossigeno e della temperatura<\/li>\n\n\n\n<li>Smistamento e tracciabilit\u00e0: gestione controllata e organizzazione fisica di numerose geometrie dello stampo elaborate nello stesso momento con tracciabilit\u00e0 opzionale della cronologia di produzione<\/li>\n\n\n\n<li>Polimerizzazione personalizzata: fotopolimerizzazione visibile e UV e\/o temperatura e tunnel temporizzato con tracciamento dei prodotti<\/li>\n\n\n\n<li>Sistemi totalmente integrati per l\u2019incartonamento delle confezioni di blister in confezioni secondarie pronte all\u2019uso<\/li>\n<\/ul>\n\n<\/div><\/div><\/div>\n<\/div>\n<\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"gb-container gb-container-73272086 segment-icons-wrp\"><div class=\"gb-inside-container\">\n<div class=\"gb-container gb-container-16f9090d\"><div class=\"gb-inside-container\">\n\n<h2 class=\"gb-headline gb-headline-5aebf343 gb-headline-text\">Competenza<\/h2>\n\n<\/div><\/div>\n\n<div class=\"gb-grid-wrapper gb-grid-wrapper-435906ac automation-solutions-cards\">\n<div class=\"gb-grid-column gb-grid-column-605da5ef\"><div class=\"gb-container gb-container-605da5ef\"><div class=\"gb-inside-container\">\n\n<h3 class=\"gb-headline gb-headline-68d16dde gb-headline-text\"><img loading=\"lazy\" decoding=\"async\" width=\"70\" height=\"29\" class=\"wp-image-18122\" style=\"width: 70px;\" src=\"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2024\/06\/lines.svg\" alt=\"\"> Produzione a volumi ridotti e altamente diversificati (HMLV)<\/h3>\n\n\n\n<p class=\"gb-headline gb-headline-792feee8 gb-headline-text\">Per i prodotti complessi o di nicchia e i loro requisiti e tolleranze specifici<\/p>\n\n<\/div><\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-3eb18173\"><div class=\"gb-container gb-container-3eb18173\"><div class=\"gb-inside-container\">\n\n<h3 class=\"gb-headline gb-headline-6c2a69de gb-headline-text\"><img loading=\"lazy\" decoding=\"async\" width=\"70\" height=\"29\" class=\"wp-image-18122\" style=\"width: 70px;\" src=\"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2024\/06\/lines.svg\" alt=\"\"> Soluzioni\/Prodotti oftalmici<\/h3>\n\n\n\n<p class=\"gb-headline gb-headline-0dd17fec gb-headline-text\">Preparazione secondo i pi\u00f9 rigidi standard del settore medico<\/p>\n\n<\/div><\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-536db221\"><div class=\"gb-container gb-container-536db221\"><div class=\"gb-inside-container\">\n\n<h3 class=\"gb-headline gb-headline-0d751c6c gb-headline-text\"><img loading=\"lazy\" decoding=\"async\" width=\"70\" height=\"29\" class=\"wp-image-18122\" style=\"width: 70px;\" src=\"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2024\/06\/lines.svg\" alt=\"\"> Produzione di grandi volumi di apparecchiature secondo le specifiche stabilite<\/h3>\n\n\n\n<p class=\"gb-headline gb-headline-a6e7a25c gb-headline-text\">ATS offre ai clienti la stessa disciplina di gestione dei progetti e la stessa eccellenza ingegneristica per situazioni di costruzione secondo il modello o il riferimento<\/p>\n\n<\/div><\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-9dba5739\"><div class=\"gb-container gb-container-9dba5739\"><div class=\"gb-inside-container\">\n\n<h3 class=\"gb-headline gb-headline-a367a1c3 gb-headline-text\"><img loading=\"lazy\" decoding=\"async\" width=\"70\" height=\"29\" class=\"wp-image-18122\" style=\"width: 70px;\" src=\"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2024\/06\/lines.svg\" alt=\"\"> Sistema di validazione\/visivo<\/h3>\n\n\n\n<p class=\"gb-headline gb-headline-93d024d6 gb-headline-text\">Preparazione secondo i pi\u00f9 rigidi standard del settore medico<\/p>\n\n<\/div><\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-d0850687\"><div class=\"gb-container gb-container-d0850687\"><div class=\"gb-inside-container\">\n\n<h3 class=\"gb-headline gb-headline-8bb57305 gb-headline-text\"><img loading=\"lazy\" decoding=\"async\" width=\"70\" height=\"29\" class=\"wp-image-18122\" style=\"width: 70px;\" src=\"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2024\/06\/lines.svg\" alt=\"\"> Ricette multiple<\/h3>\n\n\n\n<p class=\"gb-headline gb-headline-28f96122 gb-headline-text\">ATS pu\u00f2 supportare la tua famiglia di prodotti con numerose linee efficienti e salvaspazio<\/p>\n\n<\/div><\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-5d5a5f7d\"><div class=\"gb-container gb-container-5d5a5f7d\"><div class=\"gb-inside-container\">\n\n<h3 class=\"gb-headline gb-headline-5e362c41 gb-headline-text\"><img loading=\"lazy\" decoding=\"async\" width=\"70\" height=\"29\" class=\"wp-image-18122\" style=\"width: 70px;\" src=\"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2024\/06\/lines.svg\" alt=\"\"> Progettati per l\u2019OEE<\/h3>\n\n\n\n<p class=\"gb-headline gb-headline-138fb9fd gb-headline-text\">Costruiamo i nostri sistemi di automazione per massimizzare affidabilit\u00e0 e sostenibilit\u00e0; quindi li testiamo attentamente per provarne l\u2019efficacia<\/p>\n\n<\/div><\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-96013ec0\"><div class=\"gb-container gb-container-96013ec0\"><div class=\"gb-inside-container\">\n\n<h3 class=\"gb-headline gb-headline-e94569dd gb-headline-text\"><img loading=\"lazy\" decoding=\"async\" width=\"70\" height=\"29\" class=\"wp-image-18122\" style=\"width: 70px;\" src=\"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2024\/06\/lines.svg\" alt=\"\"> Strumenti chirurgici, flaconi e contagocce per collirio<\/h3>\n\n\n\n<p class=\"gb-headline gb-headline-c1cc4d94 gb-headline-text\">Capacit\u00e0 di ispezione che sfruttano tecniche di apprendimento automatico consentendo il movimento verso processi automatizzati<\/p>\n\n<\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"gb-container gb-container-5cd5be13\"><div class=\"gb-inside-container\">\n\n<h2 class=\"gb-headline gb-headline-13a1557b gb-headline-text\">Risorse<\/h2>\n\n\n<div class=\"gb-grid-wrapper gb-grid-wrapper-8480e12c resources-card\">\n<div class=\"gb-grid-column gb-grid-column-95787a81\"><div class=\"gb-container gb-container-95787a81 card-item\"><div class=\"gb-inside-container\">\n\n<figure class=\"gb-block-image gb-block-image-3b40d7a0\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"681\" class=\"gb-image gb-image-3b40d7a0\" src=\"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2022\/12\/FAQ-Contact-Lens-Thumb_1024x681.jpg\" alt=\"FAQ Contact Lens Thumb_1024x681\" title=\"FAQ Contact Lens Thumb_1024x681\" srcset=\"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2022\/12\/FAQ-Contact-Lens-Thumb_1024x681.jpg 1024w, https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2022\/12\/FAQ-Contact-Lens-Thumb_1024x681.jpg?resize=300,200 300w, https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2022\/12\/FAQ-Contact-Lens-Thumb_1024x681.jpg?resize=768,511 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"gb-headline gb-headline-f52fb67a gb-headline-text\">FAQ<\/p>\n\n\n\n<h3 class=\"gb-headline gb-headline-f498a039 gb-headline-text\">Cosa sentiamo dire pi\u00f9 spesso dai clienti e in fiera?<\/h3>\n\n\n<div class=\"gb-button-wrapper gb-button-wrapper-3c55f722\">\n\n<a class=\"gb-button gb-button-c35f417a gb-button-text atsls-btn\" href=\"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2023\/02\/ContactLens-FAQ_v1_1.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">DOWNLOAD<\/a>\n\n<\/div>\n<\/div><\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-45950f91\"><div class=\"gb-container gb-container-45950f91 card-item\"><div class=\"gb-inside-container\">\n\n<figure class=\"gb-block-image gb-block-image-6386350d\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"681\" class=\"gb-image gb-image-6386350d\" src=\"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2022\/12\/Contact-Lens-Thumb_1024x681-1.jpg\" alt=\"\" title=\"Contact-Lens-Thumb_1024x681-1\" srcset=\"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2022\/12\/Contact-Lens-Thumb_1024x681-1.jpg 1024w, https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2022\/12\/Contact-Lens-Thumb_1024x681-1.jpg?resize=300,200 300w, https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2022\/12\/Contact-Lens-Thumb_1024x681-1.jpg?resize=768,511 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"gb-headline gb-headline-e90d3464 gb-headline-text\">SCHEDA INFORMATIVA<\/p>\n\n\n\n<h3 class=\"gb-headline gb-headline-7ec995f2 gb-headline-text\">Le nostre lenti a contatto e le nostre capacit\u00e0 oftalmiche<\/h3>\n\n\n<div class=\"gb-button-wrapper gb-button-wrapper-515e419a\">\n\n<a class=\"gb-button gb-button-75943d0b gb-button-text atsls-btn\" href=\"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2023\/02\/ContactLens-Sellsheet_v1_1.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">DOWNLOAD<\/a>\n\n<\/div>\n<\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"gb-container gb-container-8f2b40f6 alignfull\"><div class=\"gb-inside-container\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-e38c66c3\">\n<div class=\"gb-grid-column gb-grid-column-f4ea0eac\"><div class=\"gb-container gb-container-f4ea0eac\"><div class=\"gb-inside-container\">\n\n<h2 class=\"gb-headline gb-headline-5adb5275 gb-headline-text\">Siete pronti a discutere del vostro progetto nel settore delle scienze della vita con uno specialista ATS?<\/h2>\n\n\n\n<p class=\"has-white-color has-text-color wp-block-paragraph\">Possiamo offrirvi un approccio standardizzato per soddisfare le vostre esigenze immediate o una soluzione personalizzata per l\u2019implementazione del vostro piano di automazione a lungo termine.<\/p>\n\n\n<div class=\"gb-button-wrapper gb-button-wrapper-f2e39382\">\n\n<a class=\"gb-button gb-button-c3a2e77f gb-button-text atsls-btn atsls-modal-btn\" href=\"#\" data-id=\"atsls-modal-medium\">contattateci<\/a>\n\n<\/div>\n<\/div><\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-6a420282\"><div class=\"gb-container gb-container-6a420282\"><div class=\"gb-inside-container\"><\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"gb-container gb-container-c4f2ffb8 atsls-modal atsls-modal-medium alignfull\" data-id=\"atsls-modal-medium\"><div class=\"gb-inside-container\">\n\n<h2 class=\"gb-headline gb-headline-63a91292 gb-headline-text\">CONTATTATECI<\/h2>\n\n\n\n\n<!-- iframe plugin v.6.0 wordpress.org\/plugins\/iframe\/ -->\n<iframe loading=\"lazy\" data-cookieconsent=\"ignore\" id=\"pardot-iframe\" style=\"border: 0;\" src=\"https:\/\/go.atsautomation.com\/l\/651873\/2023-04-05\/h5mk32?Source_Page=medical_devices\" width=\"100%\" frameborder=\"0\" height=\"500\" scrolling=\"yes\" class=\"iframe-class\"><\/iframe>\n\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Take this short quiz below to find out! 6 to 7 points \u2013 Your existing production seems to be meeting your needs for the most part. Stay connected to see which developments can keep you competitive. 8 to 9 points \u2013 It seems you have some areas of concern. We&#8217;d be happy to discuss options<\/p>\n","protected":false},"author":24,"featured_media":7278,"parent":11273,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/empty.php","meta":{"_acf_changed":false,"_cr_original_post":"","_cr_replace_post_id":"","_cr_replacing_post_id":"","inline_featured_image":false,"cover_image":0,"footnotes":""},"coauthors":[25],"class_list":["post-13470","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>LENTI A CONTATTO\/PRODOTTI OFTALMICI - ATS Life Sciences<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.atslifesciences.com\/it\/segmenti-di-mercato-che-serviamo\/dispositivi-medici\/lenti-a-contatto-prodotti-oftalmici\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LENTI A CONTATTO\/PRODOTTI OFTALMICI\" \/>\n<meta property=\"og:description\" content=\"Take this short quiz below to find out! 6 to 7 points \u2013 Your existing production seems to be meeting your needs for the most part. Stay connected to see which developments can keep you competitive. 8 to 9 points \u2013 It seems you have some areas of concern. We&#8217;d be happy to discuss options\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.atslifesciences.com\/it\/segmenti-di-mercato-che-serviamo\/dispositivi-medici\/lenti-a-contatto-prodotti-oftalmici\/\" \/>\n<meta property=\"og:site_name\" content=\"ATS Life Sciences\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-27T17:30:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2022\/12\/shutterstock_697322542_SML.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1157\" \/>\n\t<meta property=\"og:image:height\" content=\"790\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minuti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Catherine Thacker\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.atslifesciences.com\\\/it\\\/segmenti-di-mercato-che-serviamo\\\/dispositivi-medici\\\/lenti-a-contatto-prodotti-oftalmici\\\/\",\"url\":\"https:\\\/\\\/www.atslifesciences.com\\\/it\\\/segmenti-di-mercato-che-serviamo\\\/dispositivi-medici\\\/lenti-a-contatto-prodotti-oftalmici\\\/\",\"name\":\"LENTI A CONTATTO\\\/PRODOTTI OFTALMICI - ATS Life Sciences\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.atslifesciences.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.atslifesciences.com\\\/it\\\/segmenti-di-mercato-che-serviamo\\\/dispositivi-medici\\\/lenti-a-contatto-prodotti-oftalmici\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.atslifesciences.com\\\/it\\\/segmenti-di-mercato-che-serviamo\\\/dispositivi-medici\\\/lenti-a-contatto-prodotti-oftalmici\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.atslifesciences.com\\\/wp-content\\\/uploads\\\/sites\\\/63\\\/2022\\\/12\\\/shutterstock_697322542_SML.jpg\",\"datePublished\":\"2023-03-28T15:25:53+00:00\",\"dateModified\":\"2025-11-27T17:30:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.atslifesciences.com\\\/it\\\/segmenti-di-mercato-che-serviamo\\\/dispositivi-medici\\\/lenti-a-contatto-prodotti-oftalmici\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.atslifesciences.com\\\/it\\\/segmenti-di-mercato-che-serviamo\\\/dispositivi-medici\\\/lenti-a-contatto-prodotti-oftalmici\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.atslifesciences.com\\\/it\\\/segmenti-di-mercato-che-serviamo\\\/dispositivi-medici\\\/lenti-a-contatto-prodotti-oftalmici\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.atslifesciences.com\\\/wp-content\\\/uploads\\\/sites\\\/63\\\/2022\\\/12\\\/shutterstock_697322542_SML.jpg\",\"contentUrl\":\"https:\\\/\\\/www.atslifesciences.com\\\/wp-content\\\/uploads\\\/sites\\\/63\\\/2022\\\/12\\\/shutterstock_697322542_SML.jpg\",\"width\":1157,\"height\":790,\"caption\":\"Colored contact lenses with water drops close up\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.atslifesciences.com\\\/it\\\/segmenti-di-mercato-che-serviamo\\\/dispositivi-medici\\\/lenti-a-contatto-prodotti-oftalmici\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.atslifesciences.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SEGMENTI DI MERCATO CHE SERVIAMO\",\"item\":\"https:\\\/\\\/www.atslifesciences.com\\\/it\\\/segmenti-di-mercato-che-serviamo\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"DISPOSITIVI MEDICI\",\"item\":\"https:\\\/\\\/www.atslifesciences.com\\\/it\\\/segmenti-di-mercato-che-serviamo\\\/dispositivi-medici\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"LENTI A CONTATTO\\\/PRODOTTI OFTALMICI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.atslifesciences.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.atslifesciences.com\\\/it\\\/\",\"name\":\"ATS Life Sciences\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.atslifesciences.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"LENTI A CONTATTO\/PRODOTTI OFTALMICI - ATS Life Sciences","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.atslifesciences.com\/it\/segmenti-di-mercato-che-serviamo\/dispositivi-medici\/lenti-a-contatto-prodotti-oftalmici\/","og_locale":"it_IT","og_type":"article","og_title":"LENTI A CONTATTO\/PRODOTTI OFTALMICI","og_description":"Take this short quiz below to find out! 6 to 7 points \u2013 Your existing production seems to be meeting your needs for the most part. Stay connected to see which developments can keep you competitive. 8 to 9 points \u2013 It seems you have some areas of concern. We&#8217;d be happy to discuss options","og_url":"https:\/\/www.atslifesciences.com\/it\/segmenti-di-mercato-che-serviamo\/dispositivi-medici\/lenti-a-contatto-prodotti-oftalmici\/","og_site_name":"ATS Life Sciences","article_modified_time":"2025-11-27T17:30:14+00:00","og_image":[{"width":1157,"height":790,"url":"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2022\/12\/shutterstock_697322542_SML.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"7 minuti","Written by":"Catherine Thacker"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.atslifesciences.com\/it\/segmenti-di-mercato-che-serviamo\/dispositivi-medici\/lenti-a-contatto-prodotti-oftalmici\/","url":"https:\/\/www.atslifesciences.com\/it\/segmenti-di-mercato-che-serviamo\/dispositivi-medici\/lenti-a-contatto-prodotti-oftalmici\/","name":"LENTI A CONTATTO\/PRODOTTI OFTALMICI - ATS Life Sciences","isPartOf":{"@id":"https:\/\/www.atslifesciences.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.atslifesciences.com\/it\/segmenti-di-mercato-che-serviamo\/dispositivi-medici\/lenti-a-contatto-prodotti-oftalmici\/#primaryimage"},"image":{"@id":"https:\/\/www.atslifesciences.com\/it\/segmenti-di-mercato-che-serviamo\/dispositivi-medici\/lenti-a-contatto-prodotti-oftalmici\/#primaryimage"},"thumbnailUrl":"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2022\/12\/shutterstock_697322542_SML.jpg","datePublished":"2023-03-28T15:25:53+00:00","dateModified":"2025-11-27T17:30:14+00:00","breadcrumb":{"@id":"https:\/\/www.atslifesciences.com\/it\/segmenti-di-mercato-che-serviamo\/dispositivi-medici\/lenti-a-contatto-prodotti-oftalmici\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.atslifesciences.com\/it\/segmenti-di-mercato-che-serviamo\/dispositivi-medici\/lenti-a-contatto-prodotti-oftalmici\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.atslifesciences.com\/it\/segmenti-di-mercato-che-serviamo\/dispositivi-medici\/lenti-a-contatto-prodotti-oftalmici\/#primaryimage","url":"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2022\/12\/shutterstock_697322542_SML.jpg","contentUrl":"https:\/\/www.atslifesciences.com\/wp-content\/uploads\/sites\/63\/2022\/12\/shutterstock_697322542_SML.jpg","width":1157,"height":790,"caption":"Colored contact lenses with water drops close up"},{"@type":"BreadcrumbList","@id":"https:\/\/www.atslifesciences.com\/it\/segmenti-di-mercato-che-serviamo\/dispositivi-medici\/lenti-a-contatto-prodotti-oftalmici\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.atslifesciences.com\/it\/"},{"@type":"ListItem","position":2,"name":"SEGMENTI DI MERCATO CHE SERVIAMO","item":"https:\/\/www.atslifesciences.com\/it\/segmenti-di-mercato-che-serviamo\/"},{"@type":"ListItem","position":3,"name":"DISPOSITIVI MEDICI","item":"https:\/\/www.atslifesciences.com\/it\/segmenti-di-mercato-che-serviamo\/dispositivi-medici\/"},{"@type":"ListItem","position":4,"name":"LENTI A CONTATTO\/PRODOTTI OFTALMICI"}]},{"@type":"WebSite","@id":"https:\/\/www.atslifesciences.com\/it\/#website","url":"https:\/\/www.atslifesciences.com\/it\/","name":"ATS Life Sciences","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.atslifesciences.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"acf":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.atslifesciences.com\/it\/wp-json\/wp\/v2\/pages\/13470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.atslifesciences.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.atslifesciences.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.atslifesciences.com\/it\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/www.atslifesciences.com\/it\/wp-json\/wp\/v2\/comments?post=13470"}],"version-history":[{"count":8,"href":"https:\/\/www.atslifesciences.com\/it\/wp-json\/wp\/v2\/pages\/13470\/revisions"}],"predecessor-version":[{"id":24985,"href":"https:\/\/www.atslifesciences.com\/it\/wp-json\/wp\/v2\/pages\/13470\/revisions\/24985"}],"up":[{"embeddable":true,"href":"https:\/\/www.atslifesciences.com\/it\/wp-json\/wp\/v2\/pages\/11273"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.atslifesciences.com\/it\/wp-json\/wp\/v2\/media\/7278"}],"wp:attachment":[{"href":"https:\/\/www.atslifesciences.com\/it\/wp-json\/wp\/v2\/media?parent=13470"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.atslifesciences.com\/it\/wp-json\/wp\/v2\/coauthors?post=13470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}